{"id":2437,"date":"2019-03-14T13:08:36","date_gmt":"2019-03-14T13:08:36","guid":{"rendered":"https:\/\/www.celec.gob.ec\/hidroagoyan\/?p=333"},"modified":"2019-03-14T13:08:36","modified_gmt":"2019-03-14T13:08:36","slug":"celec-ep-suscribio-contrato-para-los-estudios-y-diseno-del-sistema-de-transmision-nororiental-ecuatoriano","status":"publish","type":"post","link":"https:\/\/www.celec.gob.ec\/hidroagoyan\/noticias-noticias\/celec-ep-suscribio-contrato-para-los-estudios-y-diseno-del-sistema-de-transmision-nororiental-ecuatoriano\/","title":{"rendered":"CELEC EP suscribi\u00f3 contrato para los estudios y dise\u00f1o del Sistema de Transmisi\u00f3n Nororiental Ecuatoriano"},"content":{"rendered":"<p style=\"margin: 15px 0px; color: #2f2f2f; font-family: 'Roboto Condensed'; font-size: 14px; text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-332\" src=\"https:\/\/www.celec.gob.ec\/hidroagoyan\/wp-content\/uploads\/2019\/03\/transelectric.jpg\" alt=\"\" width=\"650\" height=\"368\" \/><\/p>\n<p style=\"margin: 15px 0px; color: #2f2f2f; font-family: 'Roboto Condensed'; font-size: 14px; text-align: justify;\">El pasado 06 de marzo de 2019, la Corporaci\u00f3n El\u00e9ctrica del Ecuador CELEC EP conjuntamente con Chanjiang Institute of Survey, Planning, Design and Research suscribieron un contrato para realizar los estudios y dise\u00f1o del sistema de transmisi\u00f3n nororiental ecuatoriano, el cual permitir\u00e1 suministrar energ\u00eda limpia a trav\u00e9s del Sistema Nacional de Transmisi\u00f3n a Petroamazonas EP.<\/p>\n<p><!--more--><\/p>\n<p style=\"margin: 15px 0px; color: #2f2f2f; font-family: 'Roboto Condensed'; font-size: 14px; text-align: justify;\">Este nuevo sistema de transmisi\u00f3n fortalecer\u00e1 e incrementar\u00e1 el abastecimiento de la demanda de energ\u00eda el\u00e9ctrica a Petroamazonas EP y evitar\u00e1 inversiones adicionales en generaci\u00f3n t\u00e9rmica, lo cual garantizar\u00e1 la continuidad del suministro, y con ello la producci\u00f3n permanente de petr\u00f3leo.<\/p>\n<p style=\"margin: 15px 0px; color: #2f2f2f; font-family: 'Roboto Condensed'; font-size: 14px; text-align: justify;\">Adem\u00e1s, gracias a este sistema se mejorar\u00e1n los \u00edndices de calidad en el suministro de energ\u00eda el\u00e9ctrica de la empresa de distribuci\u00f3n CNEL EP Sucumb\u00edos a sus usuarios.<\/p>\n<p style=\"margin: 15px 0px; color: #2f2f2f; font-family: 'Roboto Condensed'; font-size: 14px; text-align: justify;\">El contrato de consultor\u00eda suscrito entre CELEC EP y Chanjian Institute of Survey, Planning, Design and Research contempla la elaboraci\u00f3n de los estudios ambientales, el\u00e9ctricos y los dise\u00f1os definitivos del nuevo sistema de transmisi\u00f3n nororiental y sus interconexiones asociadas, dentro de los costos y plazos establecidos, cumpliendo con los requerimientos t\u00e9cnicos de la Corporaci\u00f3n, la calidad y normativa legal vigente.<\/p>\n<p style=\"margin: 15px 0px; color: #2f2f2f; font-family: 'Roboto Condensed'; font-size: 14px; text-align: justify;\">Los entregables de esta consultor\u00eda permitir\u00e1n que CELEC EP tenga los insumos necesarios para iniciar el proceso de contrataci\u00f3n del suministro, construcci\u00f3n, pruebas y puesta en marcha de este importante proyecto para abastecer la demanda requerida por Petroamazonas EP.<\/p>\n<p style=\"margin: 15px 0px; color: #2f2f2f; font-family: 'Roboto Condensed'; font-size: 14px; text-align: justify;\">Este nuevo sistema estar\u00e1 conformado por varios subsistemas o interconexiones:<br \/>\u2022 Interconexi\u00f3n 230 kV Shushufindi \u2013Ed\u00e9n Yuturi \u2013 Apaika nNenke\u2013 Tiputini, con sus respectiva obras.<br \/>\u2022 Interconexi\u00f3n 138 kV Shushufindi \u2013 Tarapoa, Tarapoa \u2013 Cuyabeno 69 kV, con sus respectiva obras.<br \/>\u2022 Interconexi\u00f3n Loreto \u2013 Oso 69 kV, con sus respectiva obras.<br \/>\u2022 Interconexion Shushufindi \u2013 Shushufindi Pam 69 kV, con sus respectivas obras.<\/p>\n<p style=\"margin: 15px 0px; color: #2f2f2f; font-family: 'Roboto Condensed'; font-size: 14px; text-align: justify;\">Esta gesti\u00f3n es el resultado de compromisos entre las empresas p\u00fablicas CELEC EP y Petroamazonas EP, que se formalizaron a trav\u00e9s de convenios de cooperaci\u00f3n interinstitucional en los que se establecieron una serie de acciones conjuntas para viabilizar las obras de transmisi\u00f3n necesarias para fortalecer el sector petrolero.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado 06 de marzo de 2019, la Corporaci\u00f3n El\u00e9ctrica del Ecuador CELEC EP conjuntamente con Chanjiang Institute of Survey, Planning, Design and Research suscribieron un contrato para realizar los estudios y dise\u00f1o del sistema de transmisi\u00f3n nororiental ecuatoriano, el cual permitir\u00e1 suministrar energ\u00eda limpia a trav\u00e9s del Sistema Nacional de Transmisi\u00f3n a Petroamazonas EP.<\/p>\n","protected":false},"author":1,"featured_media":2438,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-2437","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-noticias"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 18:31:01","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.celec.gob.ec\/hidroagoyan\/wp-json\/wp\/v2\/posts\/2437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.celec.gob.ec\/hidroagoyan\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.celec.gob.ec\/hidroagoyan\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.celec.gob.ec\/hidroagoyan\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.celec.gob.ec\/hidroagoyan\/wp-json\/wp\/v2\/comments?post=2437"}],"version-history":[{"count":0,"href":"https:\/\/www.celec.gob.ec\/hidroagoyan\/wp-json\/wp\/v2\/posts\/2437\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.celec.gob.ec\/hidroagoyan\/wp-json\/wp\/v2\/media\/2438"}],"wp:attachment":[{"href":"https:\/\/www.celec.gob.ec\/hidroagoyan\/wp-json\/wp\/v2\/media?parent=2437"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.celec.gob.ec\/hidroagoyan\/wp-json\/wp\/v2\/categories?post=2437"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.celec.gob.ec\/hidroagoyan\/wp-json\/wp\/v2\/tags?post=2437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}