{"id":5023,"date":"2026-05-12T19:34:00","date_gmt":"2026-05-13T00:34:00","guid":{"rendered":"https:\/\/www.celec.gob.ec\/hidroagoyan\/?p=5023"},"modified":"2026-05-13T07:35:08","modified_gmt":"2026-05-13T12:35:08","slug":"la-celec-ep-y-el-secap-capacitan-a-los-vecinos-del-canton-el-guabo-el-oro","status":"publish","type":"post","link":"https:\/\/www.celec.gob.ec\/hidroagoyan\/noticias-noticias\/la-celec-ep-y-el-secap-capacitan-a-los-vecinos-del-canton-el-guabo-el-oro\/","title":{"rendered":"La \u00a0CELEC EP y el SECAP capacitan a los vecinos del cant\u00f3n El Guabo (El Oro)"},"content":{"rendered":"\n<p class=\"has-text-align-right\"><strong>El Guabo, 12 de mayo de 2026<\/strong><br><strong>Bolet\u00edn 043<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.celec.gob.ec\/hidroagoyan\/wp-content\/uploads\/2026\/05\/IMG_0923.JPG-1024x768-1.jpg\" alt=\"\" class=\"wp-image-5024\" srcset=\"https:\/\/www.celec.gob.ec\/hidroagoyan\/wp-content\/uploads\/2026\/05\/IMG_0923.JPG-1024x768-1.jpg 1024w, https:\/\/www.celec.gob.ec\/hidroagoyan\/wp-content\/uploads\/2026\/05\/IMG_0923.JPG-1024x768-1-300x225.jpg 300w, https:\/\/www.celec.gob.ec\/hidroagoyan\/wp-content\/uploads\/2026\/05\/IMG_0923.JPG-1024x768-1-768x576.jpg 768w, https:\/\/www.celec.gob.ec\/hidroagoyan\/wp-content\/uploads\/2026\/05\/IMG_0923.JPG-1024x768-1-200x150.jpg 200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>La Corporaci\u00f3n El\u00e9ctrica del Ecuador CELEC EP, a trav\u00e9s de la Unidad de Negocio Termogas Machala, y el Servicio Ecuatoriano de Capacitaci\u00f3n Profesional (SECAP) iniciaron el programa de capacitaci\u00f3n y certificaci\u00f3n por competencias laborales, dirigido a habitantes de las parroquias Barbones, Tendales y R\u00edo Bonito, del cant\u00f3n El Guabo, zona de influencia de las centrales t\u00e9rmicas Machala I y Machala II.<\/p>\n\n\n\n<p>El acto se desarroll\u00f3 en las instalaciones del SECAP Machala, con la participaci\u00f3n de las autoridades institucionales, l\u00edderes comunitarios y beneficiarios de este programa, que es parte de las acciones de fortalecimiento social y desarrollo productivo que impulsa CELEC EP en las comunidades de su \u00e1rea de influencia.<\/p>\n\n\n\n<p>La capacitaci\u00f3n y certificaci\u00f3n beneficiar\u00e1 a 187 habitantes, a trav\u00e9s de procesos de formaci\u00f3n t\u00e9cnica y certificaci\u00f3n laboral, &nbsp;en: confecci\u00f3n de prendas de vestir, prevenci\u00f3n de riesgos el\u00e9ctricos y seguridad y salud ocupacional. De este total, 51 participantes recibir\u00e1n capacitaci\u00f3n t\u00e9cnica presencial y 136 acceder\u00e1n a certificaciones avaladas por SECAP.<\/p>\n\n\n\n<p>Cristhian Ter\u00e1n, gerente de la Unidad de Negocio CELEC EP Termogas Machala, destac\u00f3 que estas acciones permiten generar oportunidades reales de desarrollo y empleabilidad para las comunidades.<\/p>\n\n\n\n<p>Liliana Loayza Feijoo, directora Zonal 7 del SECAP, resalt\u00f3 la importancia de la articulaci\u00f3n interinstitucional para fortalecer las capacidades t\u00e9cnicas y productivas de la ciudadan\u00eda. La iniciativa representa una inversi\u00f3n de USD 9.860 y forma parte de los programas de responsabilidad social y compromisos establecidos dentro del Plan de Manejo Ambiental de Termogas Machala.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Guabo, 12 de mayo de 2026Bolet\u00edn 043 La Corporaci\u00f3n El\u00e9ctrica del Ecuador CELEC EP, a trav\u00e9s de la Unidad de Negocio Termogas Machala, y el Servicio Ecuatoriano de Capacitaci\u00f3n Profesional (SECAP) iniciaron el programa de capacitaci\u00f3n y certificaci\u00f3n por competencias laborales, dirigido a habitantes de las parroquias Barbones, Tendales y R\u00edo Bonito, del cant\u00f3n [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":5024,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[7],"tags":[17,27,20],"class_list":["post-5023","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-noticias","tag-celec-ep","tag-energia-renovable","tag-sector-electrico"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 17:39:50","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.celec.gob.ec\/hidroagoyan\/wp-json\/wp\/v2\/posts\/5023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.celec.gob.ec\/hidroagoyan\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.celec.gob.ec\/hidroagoyan\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.celec.gob.ec\/hidroagoyan\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.celec.gob.ec\/hidroagoyan\/wp-json\/wp\/v2\/comments?post=5023"}],"version-history":[{"count":1,"href":"https:\/\/www.celec.gob.ec\/hidroagoyan\/wp-json\/wp\/v2\/posts\/5023\/revisions"}],"predecessor-version":[{"id":5025,"href":"https:\/\/www.celec.gob.ec\/hidroagoyan\/wp-json\/wp\/v2\/posts\/5023\/revisions\/5025"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.celec.gob.ec\/hidroagoyan\/wp-json\/wp\/v2\/media\/5024"}],"wp:attachment":[{"href":"https:\/\/www.celec.gob.ec\/hidroagoyan\/wp-json\/wp\/v2\/media?parent=5023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.celec.gob.ec\/hidroagoyan\/wp-json\/wp\/v2\/categories?post=5023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.celec.gob.ec\/hidroagoyan\/wp-json\/wp\/v2\/tags?post=5023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}